{"id":4726,"date":"2025-01-09T18:03:00","date_gmt":"2025-01-09T11:03:00","guid":{"rendered":"https:\/\/three-seasons-properties.com\/?post_type=vs-test&#038;p=4726"},"modified":"2025-01-26T14:43:31","modified_gmt":"2025-01-26T07:43:31","slug":"6-bed-palace-with-breath-taking-ocean-view-in-chaweng","status":"publish","type":"vs-test","link":"https:\/\/three-seasons-properties.com\/fr\/villa-for-sale\/6-bed-palace-with-breath-taking-ocean-view-in-chaweng\/","title":{"rendered":"Palais de 6 chambres avec vue imprenable sur l&#039;oc\u00e9an \u00e0 Chaweng."},"content":{"rendered":"<p>Palais de 6 chambres avec vue imprenable sur l&#039;oc\u00e9an \u00e0 Chaweng.<\/p>\n<p>Construite de mani\u00e8re unique sur les pentes au-dessus de Chaweng Noi, cette villa vous accueille non seulement pour profiter de la vue imprenable sur la baie, mais encore plus pour la combinaison unique d&#039;une hospitalit\u00e9 priv\u00e9e, d&#039;une architecture moderne et d&#039;\u00e9quipements uniques.<br \/>\nCette propri\u00e9t\u00e9 pr\u00e9sente une architecture ultra-moderne avec 6 chambres, un design \u00e9l\u00e9gant, une piscine \u00e0 d\u00e9bordement avec vue sur la mer, un billard sur place, un cin\u00e9ma et bien d&#039;autres. Le design spacieux, clair et \u00e9l\u00e9gant capture la beaut\u00e9 du paysage et offre une vue lumineuse sur la beaut\u00e9 \u00e9tonnante de la baie de Chaweng tout au long de la journ\u00e9e et de la nuit.<\/p>\n<p>Situ\u00e9e \u00e0 seulement quelques minutes de la vie anim\u00e9e de Koh Samui et du front de mer, la villa allie un design et une architecture modernes au charme d&#039;un service priv\u00e9 dans sa retraite luxueuse offrant un acc\u00e8s sur place \u00e0 un monde de divertissement, de bien-\u00eatre et de s\u00e9r\u00e9nit\u00e9.<\/p>\n<p>Prix demand\u00e9 : 109 000 000 THB<\/p>\n<p>Ne manquez pas cette splendide opportunit\u00e9 et r\u00e9servez d\u00e8s maintenant votre visite.<\/p>","protected":false},"author":7,"featured_media":4727,"menu_order":0,"template":"","meta":{"inline_featured_image":false,"footnotes":""},"categories":[75],"tags":[],"class_list":["post-4726","vs-test","type-vs-test","status-publish","has-post-thumbnail","hentry","category-sold"],"acf":[],"_links":{"self":[{"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/vs-test\/4726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/vs-test"}],"about":[{"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/types\/vs-test"}],"author":[{"embeddable":true,"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/vs-test\/4726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/media\/4727"}],"wp:attachment":[{"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/media?parent=4726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/categories?post=4726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/three-seasons-properties.com\/fr\/wp-json\/wp\/v2\/tags?post=4726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}